{"id":24770,"date":"2015-07-06T16:14:00","date_gmt":"2015-07-06T16:14:00","guid":{"rendered":"http:\/\/marketingisdead.blogspirit.com\/archive\/2015\/07\/06\/nudge-vous-avez-dit-nudge-3051385.html"},"modified":"2015-07-06T16:14:00","modified_gmt":"2015-07-06T16:14:00","slug":"nudge-vous-avez-dit-nudge","status":"publish","type":"post","link":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/","title":{"rendered":"Nudge, vous avez dit Nudge ?"},"content":{"rendered":"<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong><img id=\"media-874227\" style=\"float: left; margin: 0.2em 1.4em 0.7em 0;\" title=\"\" src=\"https:\/\/i0.wp.com\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg?w=1060\" alt=\"Nudge marketing.jpg\" data-recalc-dims=\"1\" \/>Eric Singler <\/strong>vient de publier&nbsp;: <em>Nudge marketing : Comment changer efficacement les comportements<\/em>. Petit interview pour pr\u00e9ciser quelques concepts.<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong>MarketingIsDead :<\/strong> <em>En deux mots, c\u2019est quoi le Nudge Marketing, et quelles en sont les origines&nbsp;?<\/em><\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong>Eric Singler :<\/strong> Le Nudge, c&rsquo;est le <em>\u00ab&nbsp;coup de pouce&nbsp;\u00bb<\/em>, l&rsquo;incitation douce qui encourage les individus \u00e0 adopter un nouveau comportement b\u00e9n\u00e9fique pour eux-m\u00eames, la collectivit\u00e9 ou la plan\u00e8te. Des actions apparemment anecdotiques mais dont l&rsquo;efficacit\u00e9 est formidable. Comment, par exemple, g\u00e9n\u00e9rer 96000 adh\u00e9sions suppl\u00e9mentaires \u00e0 un programme de dons d&rsquo;organe en changeant une phrase du site <a href=\"http:\/\/gov.uk\" target=\"_blank\">gov.uk<\/a> ou r\u00e9duire de 250 millions de dollars la consommation \u00e9nerg\u00e9tique de foyers en mettant un Smiley et un comparatif de consommation sur une facture. L&rsquo;approche est n\u00e9e du livre seminal<em> Nudge<\/em> de 2 professeurs Am\u00e9ricains, Richard Thaler et Cass Sunstein publi\u00e9 en 2008.<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong>MarketingIsDead :<\/strong> <em>Damasio a bien soulign\u00e9 dans l\u2019Erreur de Descartes, qu\u2019il n\u2019\u00e9tait pas possible de s\u00e9parer raison et \u00e9motions&nbsp;: comment un sp\u00e9cialiste des \u00e9tudes marketing comme toi peut-il les r\u00e9concilier&nbsp;?<\/em><\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Tu as raison, la base du Nudge, c&rsquo;est 40 ans de recherche exp\u00e9rimentale &#8211; La Behavioral Economics &#8211; qui a remis en cause la vision d&rsquo;un homo economicus qui d\u00e9cide rationnellement \u00e0 partir d&rsquo;une information rigoureusement analys\u00e9e et de pr\u00e9f\u00e9rences clairement \u00e9tablies. Nous sommes fondamentalement influenc\u00e9s par nos \u00e9motions, des illogiques de d\u00e9cision, le comportement des autres et le contexte dans lequel nous prenons nos d\u00e9cisions. En \u00e9tude, il faut donc tenter d\u2019observer plut\u00f4t que de questionner, de mettre en contexte r\u00e9el pour \u00e9viter les biais situationnels, de tenter d&rsquo;appr\u00e9hender les ph\u00e9nom\u00e8nes de compr\u00e9hension spontan\u00e9e plut\u00f4t que de faire rationaliser, de faire agir plut\u00f4t que de s&rsquo;int\u00e9resser aux attitudes et intentions \u2026<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong>MarketingIsDead :<\/strong> <em>Alors que bien souvent nous pensons dominer rationnellement nos choix, en fait, nous ob\u00e9issons \u00e0 des m\u00e9caniques totalement pr\u00e9visibles&nbsp;: un marketing qui s\u2019appuie sur de telles connaissances n\u2019est-il pas antisocial, voire dangereux&nbsp;? Que reste-t-il du libre choix des citoyens&nbsp;?<\/em><\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Les behavioral Economists cherchent \u00e0 faire comprendre au plus grand nombre la r\u00e9alit\u00e9 des facteurs qui nous influencent afin que justement cette conscience nous permette, en tant qu&rsquo;individu, de prendre des d\u00e9cisions meilleures pour nous-m\u00eames ou notre environnement.&nbsp;<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Le Nudge se veut \u00e9galement profond\u00e9ment \u00e9thique \u00e0 la fois dans sa mission \u2013 aider \u00e0 prendre des d\u00e9cisions vertueuses et b\u00e9n\u00e9fiques &#8211; et dans l&rsquo;existence de garde-fous sur les m\u00e9caniques utilis\u00e9es. Le comportement vis\u00e9 et les m\u00e9caniques utilis\u00e9es doivent \u00eatre explicables aux \u00ab&nbsp;Nudg\u00e9s&nbsp;\u00bb de mani\u00e8re transparente sinon il y a probl\u00e8me.<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Apr\u00e8s, comme toute technique elle peut \u00eatre utilis\u00e9e pour le meilleur ou pour le pire. Mais je pense pour ma part que le marketing ne peut \u00eatre que responsable s&rsquo;il veut accompagner efficacement des entreprises qui doivent savoir combiner business et \u00e9thique pour \u00eatre durablement performantes.<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong>MarketingIsDead :<\/strong> <em>Le Nudge peut \u00e9galement s\u2019appliquer aux politiques publiques&nbsp;: pour une meilleure efficacit\u00e9 de nos administrations ou dans une vision plus \u00ab&nbsp;Big Brother&nbsp;\u00bb&nbsp;?<\/em><\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Oui le Nudge s&rsquo;applique parfaitement \u00e0 l&rsquo;univers des politiques publiques. C&rsquo;est une 4<sup>\u00e8me<\/sup> voie d&rsquo;influence des comportements qui vient en compl\u00e9ment de la loi, des incitations \u00e9conomiques et de l&rsquo;information. Le Nudge cherche a rendre plus efficaces les politiques publiques en aidant aux changements comportementaux souhait\u00e9s. Recherche d&rsquo;efficacit\u00e9 \u00e0 une \u00e9poque ou chaque euro d\u00e9pens\u00e9 se doit d&rsquo;\u00eatre utile a la collectivit\u00e9, oui ! Big brother non, sauf \u00e0 consid\u00e9rer que toute action de l&rsquo;Etat est en soi ill\u00e9gitime .<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\"><strong>MarketingIsDead :<\/strong> <em>Si on applique parfaitement les th\u00e9ories du Nudge, on peut se passer \u2026 d\u2019\u00e9tudes marketing .<\/em><\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Les \u00e9tudes sont au contraire \u00e0 la base du Nudge. Un Nudge n&rsquo;est efficace qu\u2019\u00e0 partir du moment ou il l\u00e8ve une barri\u00e8re qui bloque l&rsquo;adoption du comportement souhait\u00e9. Et ce sont les \u00e9tudes \u2013 notamment Ethno \u2013 qui vont r\u00e9v\u00e9ler ces blocages. Et, apr\u00e8s avoir identifier des id\u00e9es de Nudges, il va falloir prouver leur efficacit\u00e9 avant de les d\u00e9ployer globalement. Donc des &nbsp;exp\u00e9rimentations comportementales en fin de process.<\/span><\/p>\n<p><span style=\"font-family: verdana,geneva; font-size: small;\">Les \u00e9tudes sont donc au c\u0153ur de la d\u00e9marche Nudge en combinaison avec des approches inspir\u00e9es de Design Thinking, de cr\u00e9ativit\u00e9 et de consulting.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eric Singler vient de publier&nbsp;: Nudge marketing : Comment changer efficacement les comportements. Petit interview pour pr\u00e9ciser quelques concepts. MarketingIsDead : En deux mots, c\u2019est quoi le Nudge Marketing, et quelles en sont les origines&nbsp;? Eric Singler : Le Nudge, c&rsquo;est le \u00ab&nbsp;coup de pouce&nbsp;\u00bb,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[149],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nudge, vous avez dit Nudge ? - Marketing is Dead<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nudge, vous avez dit Nudge ? - Marketing is Dead\" \/>\n<meta property=\"og:description\" content=\"Eric Singler vient de publier&nbsp;: Nudge marketing : Comment changer efficacement les comportements. Petit interview pour pr\u00e9ciser quelques concepts. MarketingIsDead : En deux mots, c\u2019est quoi le Nudge Marketing, et quelles en sont les origines&nbsp;? Eric Singler : Le Nudge, c&rsquo;est le \u00ab&nbsp;coup de pouce&nbsp;\u00bb,...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketing is Dead\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-06T16:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing is Dead\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/#website\",\"url\":\"http:\/\/consumerinsight.eu\/marketingisdead\/\",\"name\":\"Marketing is Dead\",\"description\":\"Le marketing est mort, vive le marketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/consumerinsight.eu\/marketingisdead\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg\",\"contentUrl\":\"http:\/\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#webpage\",\"url\":\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/\",\"name\":\"Nudge, vous avez dit Nudge ? - Marketing is Dead\",\"isPartOf\":{\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#primaryimage\"},\"datePublished\":\"2015-07-06T16:14:00+00:00\",\"dateModified\":\"2015-07-06T16:14:00+00:00\",\"author\":{\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/#\/schema\/person\/4b45a7cf63a0e61687a577f5bed48d86\"},\"breadcrumb\":{\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/consumerinsight.eu\/marketingisdead\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nudge, vous avez dit Nudge ?\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/#\/schema\/person\/4b45a7cf63a0e61687a577f5bed48d86\",\"name\":\"Marketing is Dead\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/consumerinsight.eu\/marketingisdead\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/fc33689a54cb0b0978c5d72999ffbbda?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/fc33689a54cb0b0978c5d72999ffbbda?s=96&d=mm&r=g\",\"caption\":\"Marketing is Dead\"},\"url\":\"http:\/\/consumerinsight.eu\/marketingisdead\/administrateur\/marketing-is-dead\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nudge, vous avez dit Nudge ? - Marketing is Dead","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/","og_locale":"fr_FR","og_type":"article","og_title":"Nudge, vous avez dit Nudge ? - Marketing is Dead","og_description":"Eric Singler vient de publier&nbsp;: Nudge marketing : Comment changer efficacement les comportements. Petit interview pour pr\u00e9ciser quelques concepts. MarketingIsDead : En deux mots, c\u2019est quoi le Nudge Marketing, et quelles en sont les origines&nbsp;? Eric Singler : Le Nudge, c&rsquo;est le \u00ab&nbsp;coup de pouce&nbsp;\u00bb,...","og_url":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/","og_site_name":"Marketing is Dead","article_published_time":"2015-07-06T16:14:00+00:00","og_image":[{"url":"http:\/\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg"}],"twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Marketing is Dead","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/consumerinsight.eu\/marketingisdead\/#website","url":"http:\/\/consumerinsight.eu\/marketingisdead\/","name":"Marketing is Dead","description":"Le marketing est mort, vive le marketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/consumerinsight.eu\/marketingisdead\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#primaryimage","inLanguage":"fr-FR","url":"http:\/\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg","contentUrl":"http:\/\/marketingisdead.blogspirit.com\/media\/00\/01\/3815653945.jpg"},{"@type":"WebPage","@id":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#webpage","url":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/","name":"Nudge, vous avez dit Nudge ? - Marketing is Dead","isPartOf":{"@id":"http:\/\/consumerinsight.eu\/marketingisdead\/#website"},"primaryImageOfPage":{"@id":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#primaryimage"},"datePublished":"2015-07-06T16:14:00+00:00","dateModified":"2015-07-06T16:14:00+00:00","author":{"@id":"http:\/\/consumerinsight.eu\/marketingisdead\/#\/schema\/person\/4b45a7cf63a0e61687a577f5bed48d86"},"breadcrumb":{"@id":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/consumerinsight.eu\/marketingisdead\/nudge-vous-avez-dit-nudge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/consumerinsight.eu\/marketingisdead\/"},{"@type":"ListItem","position":2,"name":"Nudge, vous avez dit Nudge ?"}]},{"@type":"Person","@id":"http:\/\/consumerinsight.eu\/marketingisdead\/#\/schema\/person\/4b45a7cf63a0e61687a577f5bed48d86","name":"Marketing is Dead","image":{"@type":"ImageObject","@id":"http:\/\/consumerinsight.eu\/marketingisdead\/#personlogo","inLanguage":"fr-FR","url":"http:\/\/0.gravatar.com\/avatar\/fc33689a54cb0b0978c5d72999ffbbda?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/fc33689a54cb0b0978c5d72999ffbbda?s=96&d=mm&r=g","caption":"Marketing is Dead"},"url":"http:\/\/consumerinsight.eu\/marketingisdead\/administrateur\/marketing-is-dead\/"}]}},"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7oQEP-6rw","jetpack-related-posts":[{"id":24776,"url":"http:\/\/consumerinsight.eu\/marketingisdead\/linbound-marketing-selon-la-strategie-du-sherpa\/","url_meta":{"origin":24770,"position":0},"title":"L\u2019Inbound Marketing selon la Strat\u00e9gie du Sherpa","date":"19 mars 2015","format":false,"excerpt":"Gabriel Szapiro vient de publier L\u2019Inbound Marketing selon la Strat\u00e9gie du Sherpa\u00a0; rencontre avec le fondateur de l\u2019agence Saphir.MarketingIsDead : Tu viens de publier L\u2019Inbound Marketing selon la Strat\u00e9gie du Sherpa\u00a0: en deux mot, c\u2019est quoi, l\u2019Inbound Marketing\u00a0?Gabriel Szapiro\u00a0: L\u2019Inbound Marketing\u00a0 consiste \u00e0 \u00ab Faire venir \u00e0 soi les clients\u2026","rel":"","context":"Dans &quot;Interviews&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26149,"url":"http:\/\/consumerinsight.eu\/marketingisdead\/rise-quel-fundraising-pour-une-epoque-enervee\/","url_meta":{"origin":24770,"position":1},"title":"Rise ! Quel fundraising pour une \u00e9poque \u00e9nerv\u00e9e ?","date":"27 f\u00e9vrier 2020","format":"gallery","excerpt":"Plus encore que les marques, les associations se heurtent au manque de confiance et au d\u00e9sengagement de leurs publics, et peinent de plus en plus \u00e0 collecter des dons. Le secteur du bien commun est confront\u00e9 \u00e0 un double d\u00e9fi : F\u00e9d\u00e9rer de nouvelles populations de donateurs et de soutiensInventer\u2026","rel":"","context":"Dans &quot;Actualit\u00e9&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/consumerinsight.eu\/marketingisdead\/wp-content\/uploads\/sites\/2\/2020\/02\/photo-1518601794912-1af91724e528-450x563.jpeg?fit=450%2C563&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25140,"url":"http:\/\/consumerinsight.eu\/marketingisdead\/objets-connectes-marketing-lassurance-entre-attentes-realites\/","url_meta":{"origin":24770,"position":2},"title":"Objets connect\u00e9s et marketing dans l\u2019assurance\u00a0: entre attentes et r\u00e9alit\u00e9s","date":"20 septembre 2016","format":"gallery","excerpt":"Notre Soci\u00e9t\u00e9 a connu au cours de ces 20 derni\u00e8res ann\u00e9es plus de bouleversements que les 50 pr\u00e9c\u00e9dentes ; en particulier des bouleversements brutaux, fondamentaux, qui remettent en cause les bases m\u00eame de notre vie, tant personnelle que sociale. Ces changements impactent au premier plan les acteurs du marketing dont\u2026","rel":"","context":"Dans &quot;Actualit\u00e9&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/consumerinsight.eu\/marketingisdead\/wp-content\/uploads\/sites\/2\/2016\/09\/La-Mother-et-la-Perceuse.jpg?fit=640%2C426&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":26064,"url":"http:\/\/consumerinsight.eu\/marketingisdead\/le-rgpd-ils-sen-foutent-un-peu-tous\/","url_meta":{"origin":24770,"position":3},"title":"Le RGPD, ils s\u2019en foutent un peu tous !","date":"22 novembre 2019","format":"gallery","excerpt":"\u00ab\u00a0Les internautes doivent \u00eatre inform\u00e9s et donner leur consentement pr\u00e9alablement \u00e0 l'insertion de traceurs. Ils doivent disposer d'une possibilit\u00e9 de choisir de ne pas \u00eatre trac\u00e9s lorsqu'ils visitent un site ou utilisent une application. Les \u00e9diteurs ont donc l'obligation de solliciter au pr\u00e9alable le consentement des utilisateurs\u00a0\u00bb, dixit la Cnil.\u2026","rel":"","context":"Dans &quot;Coups de gueule&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/consumerinsight.eu\/marketingisdead\/wp-content\/uploads\/sites\/2\/2019\/11\/Thin-and-Crispy-Chocolate-Chip-Cookies-2.jpg?fit=1200%2C928&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":24773,"url":"http:\/\/consumerinsight.eu\/marketingisdead\/microdon-vainqueur-du-grand-prix-start-up-2014-de-ladetem\/","url_meta":{"origin":24770,"position":4},"title":"microDON, vainqueur du Grand Prix Start-up 2014 de l&rsquo;Adetem","date":"22 juin 2015","format":false,"excerpt":"Le 2 juillet 2015, lors de la 10\u00e8me Nuit du Marketing, seront remis les Prix de l'Excellence Marketing by Adetem\u00a0; rencontre avec le vainqueur Grand Prix Start-up 2014, microDON et son Directeur G\u00e9n\u00e9ral et Cofondateur Olivier Cueille.MarketingIsDead : Olivier, en deux mots, c\u2019est quoi microDON ?En deux mots, C'est de\u2026","rel":"","context":"Dans &quot;Interviews&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24784,"url":"http:\/\/consumerinsight.eu\/marketingisdead\/pierre-bellanger-et-la-souverainete-numerique\/","url_meta":{"origin":24770,"position":5},"title":"Pierre Bellanger et La souverainet\u00e9 num\u00e9rique","date":"24 mars 2014","format":false,"excerpt":"Pierre Bellanger vient de publier La souverainet\u00e9 num\u00e9rique, un ouvrage \u00e0 la fois passionnant et d\u00e9routant, parce que par certains aspects, tr\u00e8s pessimiste\u00a0; rencontre avec le fondateur de Skyrock.MarketingIsDead : Nous sommes des nains du num\u00e9rique face aux am\u00e9ricains\u00a0! Google, Facebook, Microsoft\u00a0et quelques autres dominent l\u2019\u00e9conomie num\u00e9rique, ne nous laissant\u2026","rel":"","context":"Dans &quot;Interviews 2.0&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/posts\/24770"}],"collection":[{"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/comments?post=24770"}],"version-history":[{"count":0,"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/posts\/24770\/revisions"}],"wp:attachment":[{"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/media?parent=24770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/categories?post=24770"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/consumerinsight.eu\/marketingisdead\/wp-json\/wp\/v2\/tags?post=24770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}